{"id":259,"count":2,"description":"","link":"https:\/\/erichandemi.com\/ja\/category\/%e3%83%96%e3%83%ad%e3%82%b0\/","name":"\u30d6\u30ed\u30b0","slug":"%e3%83%96%e3%83%ad%e3%82%b0","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u30d6\u30ed\u30b0 Archives - Erich &amp; Emi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erichandemi.com\/ja\/category\/\u30d6\u30ed\u30b0\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30d6\u30ed\u30b0 Archives - Erich &amp; Emi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erichandemi.com\/ja\/category\/\u30d6\u30ed\u30b0\/\" \/>\n<meta property=\"og:site_name\" content=\"Erich &amp; Emi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/erichandemi.com\\\/ja\\\/category\\\/%e3%83%96%e3%83%ad%e3%82%b0\\\/\",\"url\":\"https:\\\/\\\/erichandemi.com\\\/ja\\\/category\\\/%e3%83%96%e3%83%ad%e3%82%b0\\\/\",\"name\":\"\u30d6\u30ed\u30b0 Archives - Erich &amp; Emi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erichandemi.com\\\/ja\\\/#website\"},\"inLanguage\":\"ja\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erichandemi.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/erichandemi.com\\\/ja\\\/\",\"name\":\"Erich &amp; Emi\",\"description\":\"Christian Missionaries to Osaka, Japan. Missions development, training and church building.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erichandemi.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u30d6\u30ed\u30b0 Archives - Erich &amp; Emi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erichandemi.com\/ja\/category\/\u30d6\u30ed\u30b0\/","og_locale":"ja_JP","og_type":"article","og_title":"\u30d6\u30ed\u30b0 Archives - Erich &amp; Emi","og_url":"https:\/\/erichandemi.com\/ja\/category\/\u30d6\u30ed\u30b0\/","og_site_name":"Erich &amp; Emi","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/erichandemi.com\/ja\/category\/%e3%83%96%e3%83%ad%e3%82%b0\/","url":"https:\/\/erichandemi.com\/ja\/category\/%e3%83%96%e3%83%ad%e3%82%b0\/","name":"\u30d6\u30ed\u30b0 Archives - Erich &amp; Emi","isPartOf":{"@id":"https:\/\/erichandemi.com\/ja\/#website"},"inLanguage":"ja"},{"@type":"WebSite","@id":"https:\/\/erichandemi.com\/ja\/#website","url":"https:\/\/erichandemi.com\/ja\/","name":"Erich &amp; Emi","description":"Christian Missionaries to Osaka, Japan. Missions development, training and church building.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erichandemi.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/erichandemi.com\/ja\/wp-json\/wp\/v2\/categories\/259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erichandemi.com\/ja\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/erichandemi.com\/ja\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/erichandemi.com\/ja\/wp-json\/wp\/v2\/posts?categories=259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}